{"id":2684,"date":"2023-11-23T19:02:40","date_gmt":"2023-11-23T19:02:40","guid":{"rendered":"https:\/\/sadet-ve.org\/?p=2684"},"modified":"2023-11-23T19:02:41","modified_gmt":"2023-11-23T19:02:41","slug":"41-aniversario-la-sociedad-anticancerosa-del-estado-trujillo-sadet","status":"publish","type":"post","link":"https:\/\/sadet-ve.org\/index.php\/2023\/11\/41-aniversario-la-sociedad-anticancerosa-del-estado-trujillo-sadet\/","title":{"rendered":"41 aniversario la Sociedad Anticancerosa del Estado Trujillo SADET"},"content":{"rendered":"\n<p>En el marco de la celebraci\u00f3n de nuestros 41 a\u00f1os la Sociedad Anticancerosa del Estado Trujillo SADET, se realizar\u00e1n un ciclo de conferencias durante la semana aniversario comprendida entre el 27 de noviembre el 01 de diciembre de 2023, las misma se llevar\u00e1n a cabo en el Sal\u00f3n de usos m\u00faltiples Dr. Jacobo Senior C. en nuestras instalaciones ubicadas en la av. 13 con calle 6, diagonal al HospitalCentral de Valera. <\/p>\n\n\n\n<p><strong>Cronograma semana aniversario:<\/strong><\/p>\n\n\n\n<p><strong>27\/11\/2023<\/strong><\/p>\n\n\n\n<p>10:00 am. Apertura de la programaci\u00f3n. Ing. Cesar Ponce.<\/p>\n\n\n\n<p>10:30 am. Conferencia El Autorretrato en la pintura. Curiosidades. Dr. Alexis Nava.<\/p>\n\n\n\n<p><strong>28\/11\/2023<\/strong><\/p>\n\n\n\n<p>10:00 am. Conferencia Vida y obra de Rafael Rangel. Psic\u00f3loga cl\u00ednica Eddy Luz Canel\u00f3n Gonz\u00e1lez.<\/p>\n\n\n\n<p>11:00 am. Conferencia Vida y obra del Dr. Jos\u00e9 Gregorio Hern\u00e1ndez. Dr. Ra\u00fal D\u00edaz Casta\u00f1eda.<\/p>\n\n\n\n<p><strong>29\/11\/2023<\/strong><\/p>\n\n\n\n<p>10:00 am. Sorteo de la rifa Pro Fondos de la SADET.<\/p>\n\n\n\n<p><strong>30\/11\/2023<\/strong><\/p>\n\n\n\n<p><strong>Conferencias \u2013 Invitados nacionales.<\/strong><\/p>\n\n\n\n<p>10:00 am. Conferencias Dr. Aulo Ortigoza. Cirujano Onc\u00f3logo.<\/p>\n\n\n\n<p>Prevenci\u00f3n primaria de las lesiones pre malignas y malignas de cuello uterino.<\/p>\n\n\n\n<p>Estadiamiento del c\u00e1ncer de cuello uterino en el siglo XXI.<\/p>\n\n\n\n<p>11:00 am. Conferencias Dr. Francisco Menolascino. Anatomopat\u00f3logo.<\/p>\n\n\n\n<p>Inmunohistoqu\u00edmica: Mitos y realidades.<\/p>\n\n\n\n<p>De la pieza al papel:<\/p>\n\n\n\n<p>Qu\u00e9 debe reportarse en el informe de patolog\u00eda en el c\u00e1ncer invasivo de mamas.<\/p>\n\n\n\n<p><strong>Conferencias cient\u00edficas<\/strong><\/p>\n\n\n\n<p><strong>01\/12\/2023<\/strong><\/p>\n\n\n\n<p>09:00 a 09:20 am. Imagenolog\u00eda en el c\u00e1ncer de mama. Dra. Elizabeth Molina. Imagen\u00f3loga.<\/p>\n\n\n\n<p>09:30 a 09:50 am. Del quir\u00f3fano al pat\u00f3logo.<\/p>\n\n\n\n<p>10:00 a 10:20 am. Leucemias. Dra. Margarita Mej\u00eda. Hemat\u00f3loga.<\/p>\n\n\n\n<p>10:30 a 11:00 am. Break.<\/p>\n\n\n\n<p>11:00 a 11:20 am. C\u00e1ncer de test\u00edculo. Dra. Ledy Hern\u00e1ndez. Ur\u00f3loga.<\/p>\n\n\n\n<p>11:30 a 11:50 am. C\u00e1ncer de pulm\u00f3n. Dr. Francisco Abreu. Neumon\u00f3logo.<\/p>\n\n\n\n<p>12:00 a 12:20 am. Retinoblastoma. Dr. Alexis Nava. Oftalm\u00f3logo.<\/p>\n\n\n\n<p>Ciclo de preguntas y respuestas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la celebraci\u00f3n de nuestros 41 a\u00f1os la Sociedad Anticancerosa del Estado Trujillo SADET, se realizar\u00e1n un ciclo de conferencias durante la semana aniversario comprendida entre el 27 de noviembre el 01 de diciembre de 2023,<\/p>\n","protected":false},"author":1,"featured_media":2687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[18],"tags":[20,22,19,21],"class_list":["post-2684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-aniversario","tag-cancer-de-mamas","tag-conferencias","tag-sadet"],"aioseo_notices":[],"uagb_featured_image_src":{"full":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias.jpg",1979,646,false],"thumbnail":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias-150x150.jpg",150,150,true],"medium":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias-300x98.jpg",300,98,true],"medium_large":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias-768x251.jpg",768,251,true],"large":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias-1024x334.jpg",1024,334,true],"1536x1536":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias-1536x501.jpg",1536,501,true],"2048x2048":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/conferencias.jpg",1979,646,false]},"uagb_author_info":{"display_name":"sadetuweb","author_link":"https:\/\/sadet-ve.org\/index.php\/author\/sadetuweb\/"},"uagb_comment_info":0,"uagb_excerpt":"En el marco de la celebraci\u00f3n de nuestros 41 a\u00f1os la Sociedad Anticancerosa del Estado Trujillo SADET, se realizar\u00e1n un ciclo de conferencias durante la semana aniversario comprendida entre el 27 de noviembre el 01 de diciembre de 2023,","_links":{"self":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts\/2684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/comments?post=2684"}],"version-history":[{"count":2,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts\/2684\/revisions"}],"predecessor-version":[{"id":2688,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts\/2684\/revisions\/2688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/media\/2687"}],"wp:attachment":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/media?parent=2684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/categories?post=2684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/tags?post=2684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}