{"id":2626,"date":"2023-11-03T16:45:51","date_gmt":"2023-11-03T16:45:51","guid":{"rendered":"https:\/\/sadet-ve.org\/?p=2626"},"modified":"2023-11-03T16:45:52","modified_gmt":"2023-11-03T16:45:52","slug":"caminata-por-la-vida-una-jornada-llena-de-alegria-y-entusiasmo","status":"publish","type":"post","link":"https:\/\/sadet-ve.org\/index.php\/2023\/11\/caminata-por-la-vida-una-jornada-llena-de-alegria-y-entusiasmo\/","title":{"rendered":"Caminata por la vida \u00a1Una jornada llena de alegr\u00eda y entusiasmo!\u00a0"},"content":{"rendered":"\n<p>Con grandes expectativas realizamos la Caminata por la Vida en apoyo a la detecci\u00f3n temprana del c\u00e1ncer de mama. Desde las 8:30 am, los participantes comenzaron a congregarse en las cercan\u00edas del Parque Los Ilustres, en el sector Las Acacias. Caminantes, senderistas y miembros de diversas organizaciones deportivas y la comunidad en general se unieron a esta noble causa.<\/p>\n\n\n\n<p>Una vez iniciado el recorrido, se llevaron a cabo sorteos de premios en los diferentes puntos de hidrataci\u00f3n establecidos. La emoci\u00f3n se palpaba en el ambiente mientras las personas recorr\u00edan el trayecto, conscientes de la importancia de la detecci\u00f3n temprana del c\u00e1ncer de mama y la promoci\u00f3n de la salud.<\/p>\n\n\n\n<p>Esta caminata no solo fue una oportunidad para promover la conciencia sobre la importancia de la detecci\u00f3n temprana, sino tambi\u00e9n para fomentar la solidaridad y el apoyo entre los participantes. Juntos, demostramos nuestro compromiso en la lucha contra esta enfermedad y enviamos un mensaje de esperanza a todas las mujeres que est\u00e1n enfrentando o han enfrentado el c\u00e1ncer de mama.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2634\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/96-1024x574.jpg\" alt=\"\" class=\"wp-image-2634\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2633\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/95-1024x574.jpg\" alt=\"\" class=\"wp-image-2633\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2632\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/87-1024x574.jpg\" alt=\"\" class=\"wp-image-2632\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2635\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/100-1024x574.jpg\" alt=\"\" class=\"wp-image-2635\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2628\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/17-1024x574.jpg\" alt=\"\" class=\"wp-image-2628\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2629\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/24-1024x574.jpg\" alt=\"\" class=\"wp-image-2629\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2630\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/52-1024x574.jpg\" alt=\"\" class=\"wp-image-2630\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2638\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/159-1024x768.jpg\" alt=\"\" class=\"wp-image-2638\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2637\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/155-1024x574.jpg\" alt=\"\" class=\"wp-image-2637\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2636\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/119-1024x574.jpg\" alt=\"\" class=\"wp-image-2636\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"2631\" src=\"https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/73-1024x574.jpg\" alt=\"\" class=\"wp-image-2631\"\/><\/figure>\n<\/figure>\n\n\n\n<p><strong>Puntos de hidrataci\u00f3n:<\/strong><\/p>\n\n\n\n<p>CC. Plaza, Mc Donald&#8217;s, CZGNB-23 Trujillo, Sucasa, Palpitar Trujillano, Panader\u00eda La Estrella, Sistema Global de Vzla y el punto de llegada en la sede de la SADET<\/p>\n\n\n\n<p><strong>En esta actividad contamos con la participaci\u00f3n de importantes organizaciones:<\/strong><\/p>\n\n\n\n<p>Asociaci\u00f3n Trujillana de Atletismo, Doctor Yaso, Zumba Fitness Plata 2, Club de Caminantes y Senderistas de Escuque, Club Harunners Escuque, Club Runners La Puerta, Crossfit Yina, Hit Combat Escuque, Team Valera Runners y el CZGNB-23 Trujillo.<\/p>\n\n\n\n<p>Nuestros agradecimientos especiales a la Ing. Mar\u00eda Gabriela Albornoz y la Corporaci\u00f3n Trujillana de Turismo, el General de Brigada Luis Guillermo Mar\u00edn Mel\u00e9ndez, Comandante del CZGNB-23 y las FAPET, por su valiosa colaboraci\u00f3n.<\/p>\n\n\n\n<p>Nuestro reconocimiento al valioso equipo de instructoras quienes amenizaron la caminata durante el recorrido en cada punto de hidrataci\u00f3n:<\/p>\n\n\n\n<p>Mary le\u00f3n, Yudith Toro, Liliana Casadiego, Rosalina D\u00edaz, Legna Colmenares, Jessica Medero, Naikely Montilla, Mileidi Medina, Mireyne Pe\u00f1a, Grisbeth Sevilla, Kimderki Aldana y Sorel Hern\u00e1ndez.<\/p>\n\n\n\n<p>Agradecemos a todos los que se sumaron a esta causa, as\u00ed como a los patrocinadores que hicieron posible este evento. Con su participaci\u00f3n y generosidad contribuyen a marcar la diferencia en la vida de muchas personas.<\/p>\n\n\n\n<p>Este evento cont\u00f3 con el patrocinio de:<\/p>\n\n\n\n<p>Gym el Centro,  Zumba plata, Bailoterapia los Ilustres, Diverlandia (Victoria Garc\u00eda), Terracota Shop, Cachapas \u00abLa Sabrosita\u00bb, Chef Runners (Danny Berr\u00edos), Club de Box Los Ilustres ( Puchungo), Parabrisas y Vidrios La Constructora, Pollos Mor\u00f3n, Confecciones Elli, Team Valera Runners, El Rey del Banano, C.A (Alexander Pacheco), Ven Cable + Internet, F\u00e1brica DT, Evolucion Gym, Posada R\u00edo Arriba, Zherynet Zhurlet\u00a0Hernandez y el Dr. Jorge Su\u00e1rez.<\/p>\n\n\n\n<p>Desde la SADET continuaremos trabajando para promover la detecci\u00f3n temprana del c\u00e1ncer de mama y apoyar a aquellos que luchan contra esta enfermedad.&nbsp;<\/p>\n\n\n\n<p>\u00a1Juntos podemos crear un impacto positivo en la vida de muchas mujeres y sus familias!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con grandes expectativas realizamos la Caminata por la Vida en apoyo a la detecci\u00f3n temprana del c\u00e1ncer de mama. Desde las 8:30 am, los participantes comenzaron a congregarse en las cercan\u00edas del Parque Los Ilustres, en el sector Las Acacias. Caminantes, senderistas y miembros de diversas organizaciones deportivas y la comunidad en general se unieron &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/sadet-ve.org\/index.php\/2023\/11\/caminata-por-la-vida-una-jornada-llena-de-alegria-y-entusiasmo\/\"> <span class=\"screen-reader-text\">Caminata por la vida \u00a1Una jornada llena de alegr\u00eda y entusiasmo!\u00a0<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","footnotes":""},"categories":[18],"tags":[],"class_list":["post-2626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"aioseo_notices":[],"uagb_featured_image_src":{"full":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-scaled.jpg",2560,784,false],"thumbnail":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-150x150.jpg",150,150,true],"medium":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-300x92.jpg",300,92,true],"medium_large":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-768x235.jpg",768,235,true],"large":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-1024x314.jpg",1024,314,true],"1536x1536":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-1536x470.jpg",1536,470,true],"2048x2048":["https:\/\/sadet-ve.org\/wp-content\/uploads\/2023\/11\/banner-caminata-2048x627.jpg",2048,627,true]},"uagb_author_info":{"display_name":"sadetuweb","author_link":"https:\/\/sadet-ve.org\/index.php\/author\/sadetuweb\/"},"uagb_comment_info":0,"uagb_excerpt":"Con grandes expectativas realizamos la Caminata por la Vida en apoyo a la detecci\u00f3n temprana del c\u00e1ncer de mama. Desde las 8:30 am, los participantes comenzaron a congregarse en las cercan\u00edas del Parque Los Ilustres, en el sector Las Acacias. Caminantes, senderistas y miembros de diversas organizaciones deportivas y la comunidad en general se unieron&hellip;","_links":{"self":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts\/2626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/comments?post=2626"}],"version-history":[{"count":2,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts\/2626\/revisions"}],"predecessor-version":[{"id":2640,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/posts\/2626\/revisions\/2640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/media\/2627"}],"wp:attachment":[{"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/media?parent=2626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/categories?post=2626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sadet-ve.org\/index.php\/wp-json\/wp\/v2\/tags?post=2626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}